{"id":2434,"date":"2024-09-30T06:34:15","date_gmt":"2024-09-30T09:34:15","guid":{"rendered":"https:\/\/elfaroonline.com.ar\/?p=2434"},"modified":"2024-09-30T06:34:15","modified_gmt":"2024-09-30T09:34:15","slug":"en-cinco-anos-se-perdieron-mas-de-92-mil-hectareas-de-bosque-y-areas-naturales-a-causa-de-los-incendios","status":"publish","type":"post","link":"https:\/\/elfaroonline.com.ar\/index.php\/2024\/09\/30\/en-cinco-anos-se-perdieron-mas-de-92-mil-hectareas-de-bosque-y-areas-naturales-a-causa-de-los-incendios\/","title":{"rendered":"En cinco a\u00f1os se perdieron m\u00e1s de 92 mil hect\u00e1reas   de bosque y \u00e1reas naturales a causa de los incendios"},"content":{"rendered":"<p class=\"v1MsoNormal\">El Gobierno de Catamarca viene trabajando en forma permanente para afrontar el accionar de los incendios que a\u00f1o tras a\u00f1o afectan a vastos sectores de la provincia. Durante los \u00faltimos cinco a\u00f1os se han perdido m\u00e1s de 92.521 hect\u00e1reas de bosques y \u00e1reas naturales como consecuencia del fuego.<\/p>\n<p class=\"v1MsoNormal\">El a\u00f1o m\u00e1s cr\u00edtico fue el 2020, cuando se registraron numerosos incendios de gran magnitud, en su mayor\u00eda ocasionados de manera intencional.\u00a0 Por tradici\u00f3n en algunas \u00e1reas rurales se estila quemar pastizales viejos para que nazca nuevo pasto situaci\u00f3n que se ha convertido como una de las principales causas de estos incendios.<\/p>\n<p class=\"v1MsoNormal\">Sin embargo, gracias a un mayor esfuerzo coordinado entre la Brigada Contra Incendios Forestales, bomberos voluntarios y con el accionar de medios a\u00e9reos, se ha logrado reducir significativamente la superficie afectada en los a\u00f1os m\u00e1s recientes.<\/p>\n<p class=\"v1MsoNormal\">Esto qued\u00f3 reflejado en el 2023 donde la cantidad de incendios fue la m\u00e1s alta en comparaci\u00f3n con a\u00f1os anteriores pero la superficie afectada fue menor. Esto se atribuye a un mejor trabajo conjunto entre los distintos organismos lo que permiti\u00f3 una intervenci\u00f3n m\u00e1s r\u00e1pida y eficiente en el control de los incendios.<\/p>\n<p class=\"v1MsoNormal\"><b>Estad\u00edsticas<\/b><\/p>\n<p class=\"v1MsoNormal\">Las estad\u00edsticas de incendios entre los a\u00f1os 2020 \u2013 2024 son las siguientes:<\/p>\n<p class=\"v1MsoNormal\">Cantidad de Incendios Forestales:<\/p>\n<p class=\"v1MsoNormal\">2020: 214<\/p>\n<p class=\"v1MsoNormal\">2021: 250<\/p>\n<p class=\"v1MsoNormal\">2022: 189<\/p>\n<p class=\"v1MsoNormal\">2023: 295<\/p>\n<p class=\"v1MsoNormal\">2024: 144 (hasta la fecha)<\/p>\n<p class=\"v1MsoNormal\">Mientras que la Superficie afectada en hect\u00e1reas es la siguiente:<\/p>\n<p class=\"v1MsoNormal\">2020: 34.219 ha.<\/p>\n<p class=\"v1MsoNormal\">2021: 13.781 ha.<\/p>\n<p class=\"v1MsoNormal\">2022: 29.247ha.<\/p>\n<p class=\"v1MsoNormal\">2023: 10.166 ha.<\/p>\n<p class=\"v1MsoNormal\">2024: 5.108 (hasta la fecha)<\/p>\n<p class=\"v1MsoNormal\">Estos datos arrojan que m\u00e1s de 90 mil hect\u00e1reas de bosques y \u00e1reas naturales se han perdido en la provincia afectando la productividad y la vegetaci\u00f3n del lugar. Estos incendios se producen en distintos puntos de la provincia.<\/p>\n<p class=\"v1MsoNormal\"><b>Causas de los Incendios<\/b><\/p>\n<p class=\"v1MsoNormal\">Las principales causas de los incendios forestales en la provincia han sido como consecuencias de distintos factores naturales y humanos.<\/p>\n<p class=\"v1MsoNormal\">El m\u00e1s grave, porque est\u00e1 calificado como intencional, es el accionar del hombre que realiza la quema de rebrote para matar plagas.<\/p>\n<p class=\"v1MsoNormal\">Tambi\u00e9n se dan por la negligencia humana como fogatas mal apagadas, colillas de cigarrillos o quemas agr\u00edcolas descontroladas.<\/p>\n<p class=\"v1MsoNormal\">Mientras que, en menores medida se dan por fen\u00f3menos naturales causados por la ca\u00edda de rayos en d\u00edas de tormenta, aunque son las menos en la provincia.<\/p>\n<p class=\"v1MsoNormal\"><b>Recursos<\/b><\/p>\n<p class=\"v1MsoNormal\">En los \u00faltimos a\u00f1os, el Gobierno de la Provincia viene trabajando para dotar a la Brigada Contra Incendios Forestales de los recursos necesarios para el r\u00e1pido accionar y as\u00ed mitigar el impacto de estos fen\u00f3menos que tanto da\u00f1o hacen a la vegetaci\u00f3n de la provincia.<\/p>\n<p class=\"v1MsoNormal\">Actualmente la brigada cuenta con un equipo especializado de 30 brigadistas capacitados para la prevenci\u00f3n y combate de incendios. Adem\u00e1s, con veh\u00edculos de combate y apoyo, entre los que se destacan 5 autobombas, 4 camionetas, 2 moto enduro, cuatriciclos, camiones cisterna.<\/p>\n<p class=\"v1MsoNormal\">Asimismo, para el apoyo a\u00e9reo se apoya mediante helic\u00f3pteros y aviones, que son esenciales para intervenir en \u00e1reas de dif\u00edcil acceso.<\/p>\n<p class=\"v1MsoNormal\"><b>Recomendaciones para la poblaci\u00f3n<\/b><\/p>\n<p class=\"v1MsoNormal\">La brigada de Lucha contra Incendios Forestales lanz\u00f3 una serie de recomendaciones para prevenir incendios:<\/p>\n<p class=\"v1MsoNormal\">1. Evitar la quema inadecuada de pastizales y desechos.<\/p>\n<p class=\"v1MsoNormal\">2. Asegurarse de que las fogatas est\u00e9n completamente apagadas antes de abandonarlas.<\/p>\n<p class=\"v1MsoNormal\">3. Mantener limpio el entorno y evitar dejar objetos inflamables, como botellas o basura.<\/p>\n<p class=\"v1MsoNormal\">Es fundamental que la poblaci\u00f3n colabore en la prevenci\u00f3n de incendios y act\u00fae de manera responsable. Si se detecta un incendio, se debe solicitar ayuda inmediata y seguir estrictamente las indicaciones de las autoridades competentes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno de Catamarca viene trabajando en forma permanente para afrontar el accionar de los incendios que a\u00f1o tras a\u00f1o afectan a vastos sectores de la provincia. Durante los \u00faltimos cinco a\u00f1os se han perdido m\u00e1s de 92.521 hect\u00e1reas de bosques y \u00e1reas naturales como consecuencia del fuego. El a\u00f1o m\u00e1s cr\u00edtico fue el 2020, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2435,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":{"0":"post-2434","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-policiales"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/elfaroonline.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/2434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elfaroonline.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elfaroonline.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elfaroonline.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elfaroonline.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=2434"}],"version-history":[{"count":2,"href":"https:\/\/elfaroonline.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/2434\/revisions"}],"predecessor-version":[{"id":2448,"href":"https:\/\/elfaroonline.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/2434\/revisions\/2448"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elfaroonline.com.ar\/index.php\/wp-json\/wp\/v2\/media\/2435"}],"wp:attachment":[{"href":"https:\/\/elfaroonline.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=2434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elfaroonline.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=2434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elfaroonline.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=2434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}