{"id":5751,"date":"2026-05-12T18:47:45","date_gmt":"2026-05-12T21:47:45","guid":{"rendered":"https:\/\/elfaroonline.com.ar\/?p=5751"},"modified":"2026-05-12T18:47:45","modified_gmt":"2026-05-12T21:47:45","slug":"catamarca-expuso-en-estados-unidos-sobre-regulacion-ambiental-y-desarrollo-sostenible-del-litio","status":"publish","type":"post","link":"https:\/\/elfaroonline.com.ar\/index.php\/2026\/05\/12\/catamarca-expuso-en-estados-unidos-sobre-regulacion-ambiental-y-desarrollo-sostenible-del-litio\/","title":{"rendered":"Catamarca expuso en Estados Unidos sobre regulaci\u00f3n ambiental y desarrollo sostenible del litio"},"content":{"rendered":"<p style=\"font-weight: 400;\"><em>La provincia particip\u00f3 en un taller internacional sobre supervisi\u00f3n regulatoria y extracci\u00f3n directa de litio realizado en Utah, junto a representantes de Naci\u00f3n, SEGEMAR y las provincias del NOA. <\/em><\/p>\n<p style=\"font-weight: 400;\">El Ministerio de Miner\u00eda particip\u00f3 del \u201cTaller de desarrollo de lineamientos de supervisi\u00f3n regulatoria para la miner\u00eda de litio y las operaciones de Extracci\u00f3n Directa de Litio (EDL), utilizando datos de los informes de impacto ambiental e intercambio t\u00e9cnico\u201d, que se realiz\u00f3 en Salt Lake City, Utah EE.UU.).<\/p>\n<p style=\"font-weight: 400;\">La delegaci\u00f3n de argentina est\u00e1 integrada por profesionales de la Secretar\u00eda de Miner\u00eda de Naci\u00f3n, del Servicio Geol\u00f3gico Minero Argentino SEGEMAR y de las provincias de Jujuy, Salta y Catamarca, representada \u00e9sta \u00faltima por la ministra de Miner\u00eda, Olga Teresita Regalado y el director del Servicio Jur\u00eddico del organismo minero, Ra\u00fal Colombo.<\/p>\n<p style=\"font-weight: 400;\">El taller reuni\u00f3 a expertos t\u00e9cnicos y jur\u00eddicos con el objetivo de fortalecer las capacidades regionales para evaluar estrategias de desarrollo de minerales cr\u00edticos, con especial \u00e9nfasis en la mejora de la toma de decisiones relacionadas con la inversi\u00f3n extranjera, la supervisi\u00f3n regulatoria y el manejo sostenible de los recursos. En este marco, Catamarca realiz\u00f3 aportes referidos al marco normativo que regula la actividad minera en la provincia, la magnitud y rigurosidad de los procesos de evaluaci\u00f3n de los informes de impacto ambiental y el rol del Estado en la maximizaci\u00f3n de los beneficios socioecon\u00f3micos derivados de la actividad minera.<\/p>\n<p style=\"font-weight: 400;\">Esta capacitaci\u00f3n forma parte de una iniciativa m\u00e1s amplia, interinstitucional, liderada por la Oficina de Asuntos Econ\u00f3micos, Energ\u00e9ticos y Empresariales (State\/EEB) del Departamento de Estado de los Estados Unidos, a trav\u00e9s de su Programa de Gobernanza Energ\u00e9tica y de Minerales (EMGP). La implementaci\u00f3n est\u00e1 a cargo del Programa de Desarrollo del Derecho Comercial (CLDP) del Departamento de Comercio de los Estados Unidos y de la Oficina de Asuntos Internacionales (DOI-INT) del Departamento del Interior de los Estados Unidos, en estrecha colaboraci\u00f3n con contrapartes gubernamentales de Argentina y Bolivia.<\/p>\n<p style=\"font-weight: 400;\">Adem\u00e1s, la delegaci\u00f3n argentina particip\u00f3 del \u201c15to Foro Bienal sobre Temas del Gran Lago Salado\u201d, un espacio de valioso intercambio de experiencias entre pares y el fortalecimiento del di\u00e1logo sobre desaf\u00edos vinculados con la gesti\u00f3n ambiental y la participaci\u00f3n comunitaria, donde se abordaron temas relacionados con la interacci\u00f3n entre m\u00faltiples operadores dedicados a la extracci\u00f3n de minerales cr\u00edticos a partir de un mismo sistema natural, as\u00ed como la necesidad de compatibilizar dicha actividad con consideraciones sociales, ambientales y ecol\u00f3gicas, promoviendo un desarrollo sostenible de los recursos.<\/p>\n<p style=\"font-weight: 400;\">Por otra parte, est\u00e1n previstas actividades de campo y sesiones t\u00e9cnicas con el Servicio Geol\u00f3gico de los Estados Unidos (USGS), centradas en la modelaci\u00f3n de aguas subterr\u00e1neas, evaluaciones integradas de disponibilidad h\u00eddrica y monitoreo en la cuenca del Gran Lago Salado. El programa tambi\u00e9n incluir\u00e1 una visita t\u00e9cnica de campo a la planta piloto de extracci\u00f3n directa (EDL) de Waterleaf Resources filial de Lilac Solutions, ubicada en el Brazo Norte del Gran Lago Salado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La provincia particip\u00f3 en un taller internacional sobre supervisi\u00f3n regulatoria y extracci\u00f3n directa de litio realizado en Utah, junto a representantes de Naci\u00f3n, SEGEMAR y las provincias del NOA. El Ministerio de Miner\u00eda particip\u00f3 del \u201cTaller de desarrollo de lineamientos de supervisi\u00f3n regulatoria para la miner\u00eda de litio y las operaciones de Extracci\u00f3n Directa de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5752,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23,21],"tags":[],"class_list":{"0":"post-5751","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-destacados","8":"category-politica"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/elfaroonline.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/5751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elfaroonline.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elfaroonline.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elfaroonline.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elfaroonline.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=5751"}],"version-history":[{"count":1,"href":"https:\/\/elfaroonline.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/5751\/revisions"}],"predecessor-version":[{"id":5753,"href":"https:\/\/elfaroonline.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/5751\/revisions\/5753"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elfaroonline.com.ar\/index.php\/wp-json\/wp\/v2\/media\/5752"}],"wp:attachment":[{"href":"https:\/\/elfaroonline.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=5751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elfaroonline.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=5751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elfaroonline.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=5751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}